{"id":23334,"date":"2025-02-05T11:20:08","date_gmt":"2025-02-05T19:20:08","guid":{"rendered":"https:\/\/clearseas.org\/?p=23334"},"modified":"2025-02-05T12:18:22","modified_gmt":"2025-02-05T20:18:22","slug":"detection-mesure-bruit-sous-marin","status":"publish","type":"post","link":"https:\/\/clearseas.org\/fr\/insights\/detection-mesure-bruit-sous-marin\/","title":{"rendered":"D\u00e9tection et mesure du bruit rayonn\u00e9 sous-marin"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\" class=\"opener\"><em><strong><mark style=\"background-color:#00aece\" class=\"has-inline-color has-gainsboro-color\"><em><strong><mark style=\"background-color:#00aece\" class=\"has-inline-color has-gainsboro-color\"><em><strong><mark style=\"background-color:#00aece\" class=\"has-inline-color has-gainsboro-color\">Cliquez pour consulter le glossaire<\/mark><\/strong><\/em><\/mark><\/strong><\/em><\/mark><\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019une des premi\u00e8res \u00e9tapes de la r\u00e9duction du <a href=\"#underwater_noise\"><mark style=\"background-color:#00aece\" class=\"has-inline-color has-gainsboro-color\">bruit rayonn\u00e9 sous-marin<\/mark><\/a> consiste \u00e0 d\u00e9tecter et \u00e0 mesurer le bruit g\u00e9n\u00e9r\u00e9 par les navires. Pour les chercheurs, des mesures pr\u00e9cises sont essentielles pour comprendre l\u2019incidence du bruit sur la vie marine et les \u00e9cosyst\u00e8mes et pour \u00e9valuer l\u2019efficacit\u00e9 des diff\u00e9rentes solutions de r\u00e9duction du bruit. Pour les gestionnaires du milieu marin et les organismes de r\u00e9glementation, les mesures sont essentielles \u00e0 la gestion des sources de bruit d\u2019origine humaine. Pour les armateurs et les exploitants de navires, ces mesures leur permettent de prendre des d\u00e9cisions \u00e9clair\u00e9es sur les technologies et les strat\u00e9gies de r\u00e9duction du bruit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les projets men\u00e9s dans le cadre de l\u2019Initiative pour des navires silencieux ont explor\u00e9 diverses m\u00e9thodes de d\u00e9tection, de mesure et d\u2019analyse du bruit rayonn\u00e9 sous-marin, y compris des solutions \u00e0 distance et embarqu\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le bruit sous-marin peut \u00eatre mesur\u00e9 \u00e0 l\u2019aide d\u2019un instrument appel\u00e9 <a href=\"#hydrophone\"><mark style=\"background-color:#00aece\" class=\"has-inline-color has-lightteal-color\">hydrophone<\/mark><\/a> (microphone sous-marin). Les hydrophones peuvent \u00eatre d\u00e9ploy\u00e9s individuellement, en groupe ou en ligne, horizontalement ou verticalement \u00e0 diff\u00e9rentes profondeurs. Pour assurer la coh\u00e9rence des mesures effectu\u00e9es par diff\u00e9rents hydrophones \u00e0 diff\u00e9rents endroits, l\u2019Organisation maritime internationale a publi\u00e9 des <a href=\"https:\/\/wwwcdn.imo.org\/localresources\/en\/Documents\/MEPC.1-Circ.906%20-%20Revised%20Guidelines%20For%20The%20Reduction%20Of%20Underwater%20Radiated%20NoiseFrom%20Shipping%20To%20Address...%20(Secretariat).pdf\">lignes directrices r\u00e9vis\u00e9es<\/a> (en anglais) qui incluent des normes de mesure du bruit<sup data-fn=\"916c8151-312f-44fa-8ba0-67dfe332d99c\" class=\"fn\"><a href=\"#916c8151-312f-44fa-8ba0-67dfe332d99c\" id=\"916c8151-312f-44fa-8ba0-67dfe332d99c-link\">1<\/a><\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsqu\u2019un navire passe devant un hydrophone, le bruit qu\u2019il \u00e9met est enregistr\u00e9. En connaissant la distance qui s\u00e9pare l\u2019hydrophone du navire \u00e0 diff\u00e9rents points, les chercheurs et les analystes de donn\u00e9es peuvent utiliser le niveau sonore enregistr\u00e9 et tenir compte de la distance parcourue et des r\u00e9flexions \u00e0 la surface de l\u2019eau et sur le fond marin pour calculer l\u2019intensit\u00e9 du son lorsqu\u2019il a quitt\u00e9 le navire. Ces mesures sonores corrig\u00e9es rendent plus pr\u00e9cises les comparaisons entre les navires, les lieux et les saisons. Les facteurs environnementaux comme le vent, les courants, la pluie et la temp\u00e9rature peuvent influencer la comparabilit\u00e9 de diff\u00e9rentes mesures sonores, m\u00eame celles prises dans la m\u00eame zone. Ces facteurs sont \u00e9galement pris en compte dans les calculs des mesures du bruit.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Que mesurent les hydrophones ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Les hydrophones d\u00e9tectent les variations de pression dans l\u2019eau caus\u00e9es par les ondes sonores. Ces capteurs convertissent les fluctuations de pression sous-marine en signaux \u00e9lectriques, qui peuvent ensuite \u00eatre analys\u00e9s pour d\u00e9terminer les propri\u00e9t\u00e9s du son comme le volume et la fr\u00e9quence. Ils fonctionnent de la m\u00eame mani\u00e8re que nos oreilles. Les mesures du bruit sous-marin provenant des navires effectu\u00e9es par les hydrophones permettent de comprendre l\u2019<a href=\"#intensity\"><mark style=\"background-color:#00aece\" class=\"has-inline-color has-gainsboro-color\">intensit\u00e9<\/mark><\/a> sonore \u2013 la quantit\u00e9 d\u2019\u00e9nergie sonore traversant une zone \u00e0 un moment donn\u00e9 \u2013 ainsi que le niveau de pression acoustique (exprim\u00e9 en <a href=\"#decibel\"><mark style=\"background-color:#00aece\" class=\"has-inline-color has-lightteal-color\">d\u00e9cibels<\/mark><\/a>) \u2013 qui repr\u00e9sente la variation moyenne de la pression carr\u00e9e du son. L\u2019\u00e9chelle des d\u00e9cibels utilise une pression de r\u00e9f\u00e9rence diff\u00e9rente dans l\u2019air et dans l\u2019eau, de sorte que la comparaison des mesures de d\u00e9cibels entre l\u2019air et l\u2019eau peut \u00eatre trompeuse \u2013 un d\u00e9cibel relativement silencieux dans l\u2019air peut \u00eatre interpr\u00e9t\u00e9 comme \u00e9lev\u00e9 dans l\u2019eau. Ces mesures servent \u00e0 d\u00e9terminer le niveau du son \u00e0 la source, ou la quantit\u00e9 de son si elle \u00e9tait mesur\u00e9e \u00e0 une distance d\u2019un m\u00e8tre (3 pieds) du navire, plut\u00f4t qu\u2019\u00e0 la distance requise lorsqu\u2019on utilise un hydrophone.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong><strong>Port\u00e9es acoustiques sous-marines<\/strong><\/strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les port\u00e9es acoustiques sous-marines sont des r\u00e9seaux d\u2019hydrophones plac\u00e9s dans l\u2019eau pour mesurer le son. Elles peuvent \u00eatre constitu\u00e9es d\u2019un seul hydrophone ou de plusieurs dispos\u00e9s le long d\u2019une ligne. Les port\u00e9es acoustiques peuvent \u00eatre permanentes ou d\u00e9ploy\u00e9es de fa\u00e7on temporaire.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"524\" src=\"https:\/\/i0.wp.com\/clearseas.org\/wp-content\/uploads\/\/Hydrophones-Cabled-In-Situ.jpg?resize=1024%2C524&#038;ssl=1\" alt=\"\" class=\"wp-image-22725\" srcset=\"https:\/\/i0.wp.com\/clearseas.org\/wp-content\/uploads\/Hydrophones-Cabled-In-Situ-scaled.jpg?resize=1024%2C524&amp;ssl=1 1024w, https:\/\/i0.wp.com\/clearseas.org\/wp-content\/uploads\/Hydrophones-Cabled-In-Situ-scaled.jpg?resize=600%2C307&amp;ssl=1 600w, https:\/\/i0.wp.com\/clearseas.org\/wp-content\/uploads\/Hydrophones-Cabled-In-Situ-scaled.jpg?resize=768%2C393&amp;ssl=1 768w, https:\/\/i0.wp.com\/clearseas.org\/wp-content\/uploads\/Hydrophones-Cabled-In-Situ-scaled.jpg?resize=1536%2C786&amp;ssl=1 1536w, https:\/\/i0.wp.com\/clearseas.org\/wp-content\/uploads\/Hydrophones-Cabled-In-Situ-scaled.jpg?resize=2048%2C1048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/clearseas.org\/wp-content\/uploads\/Hydrophones-Cabled-In-Situ-scaled.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Station d&#8217;\u00e9coute sous-marine de Boundary Pass (cr\u00e9dit\u00a0: JASCO Applied Sciences)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsqu\u2019un armateur souhaite mesurer le niveau de bruit de son navire \u00e0 l\u2019aide d\u2019une port\u00e9e acoustique, il a recours \u00e0 un processus appel\u00e9 \u00ab&nbsp;ranging&nbsp;\u00bb ou un \u00e9talonnage est effectu\u00e9. Le navire passe devant le ou les hydrophones dans une direction \u00e0 une puissance motrice constante, puis revient. L\u2019armateur peut effectuer plusieurs allers-retours pour mesurer le bruit \u00e0 diff\u00e9rents niveaux de puissance du moteur et de configuration des machines. Il peut \u00e9galement amarrer le navire \u00e0 un endroit pr\u00e9cis, \u00e9teindre tous les \u00e9quipements et moteurs, puis, une par une, allumer et \u00e9teindre diff\u00e9rentes pi\u00e8ces d\u2019\u00e9quipement. Ce proc\u00e9d\u00e9 s\u2019appelle \u00ab&nbsp;static ranging&nbsp;\u00bb ou \u00e9talonnage statique et sert \u00e0 mesurer le niveau de bruit de diff\u00e9rents \u00e9quipements. Les port\u00e9es acoustiques peuvent \u00e9galement \u00eatre utilis\u00e9es pour la surveillance passive \u00e0 long terme du bruit sous-marin produit par les navires et du bruit de fond de l\u2019oc\u00e9an, ainsi que pour l\u2019identification de la faune et de la flore marines dans la zone.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019un des principaux avantages des port\u00e9es acoustiques est que les mesures prises dans la m\u00eame port\u00e9e sont directement comparables. Cela signifie que l\u2019on peut mieux comparer diff\u00e9rents navires, comportements op\u00e9rationnels, conceptions de navires et influences saisonni\u00e8res. En outre, selon l\u2019emplacement des hydrophones, les chercheurs peuvent cr\u00e9er une image pr\u00e9cise du paysage sonore, c\u2019est-\u00e0-dire de la fa\u00e7on dont le bruit se propage dans la zone.<\/p>\n\n\n\n<details class=\"wp-block-details has-darkgrey-color has-lightteal-background-color has-text-color has-background is-layout-flow wp-container-core-details-is-layout-f342ef54 wp-block-details-is-layout-flow\" style=\"border-width:4px\"><summary>Appel aux propri\u00e9taires et exploitants de navires : participez aux mesures du bruit sous-marin !<\/summary>\n<p class=\"wp-block-paragraph\">Si vous \u00eates propri\u00e9taire ou exploitant d&#8217;un navire dans la mer des Salish et que vous souhaitez mesurer vos navires lorsqu&#8217;il transite par Boundary Pass, veuillez contacter l&#8217;\u00e9quipe QVI de Transports Canada \u00e0 l&#8217;adresse suivante : <a href=\"mailto:Marine-RDD-maritime@tc.gc.ca\">Marine-RDD-maritime@tc.gc.ca<\/a>.<\/p>\n<\/details>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-2c90304e wp-block-group-is-layout-flex\">\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><strong>Pleins feux sur la Station d\u2019\u00e9coute sous-marine du passage Boundary<\/strong><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 quelque 190\u00a0m (600 pieds) sous les couloirs de navigation de Boundary Pass \u2013 un d\u00e9troit de 23\u00a0km situ\u00e9 le long de la fronti\u00e8re entre la Colombie-Britannique (Canada) et l\u2019\u00c9tat de Washington (\u00c9tats-Unis) \u2013 se trouve une station d\u2019\u00e9coute sous-marine compos\u00e9e de plusieurs hydrophones. D\u00e9ploy\u00e9e par JASCO Applied Sciences (<a href=\"https:\/\/youtu.be\/0eIJnHnFCj8\">voir la vid\u00e9o<\/a>), la <a href=\"https:\/\/www.jasco.com\/boundary-pass-uls\">Station d\u2019\u00e9coute sous-marine de Boundary Pass<\/a> comprend deux r\u00e9seaux d\u2019hydrophones, chacun \u00e9quip\u00e9 de quatre hydrophones actifs (plus d\u2019autres en r\u00e9serve), d\u2019une cam\u00e9ra vid\u00e9o et de capteurs de temp\u00e9rature, de salinit\u00e9 et de courant de l\u2019oc\u00e9an. La station est reli\u00e9e au rivage par des c\u00e2bles \u00e0 fibres optiques, ce qui permet d\u2019\u00e9changer et de traiter les donn\u00e9es en temps r\u00e9el.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote has-darkgrey-color has-lightteal-background-color has-text-color has-background has-link-color has-small-font-size wp-elements-3fcba1941d11ba07e791e22311a755d6\" style=\"margin-top:0;margin-right:var(--wp--preset--spacing--20);margin-bottom:0;margin-left:var(--wp--preset--spacing--20);padding-top:var(--wp--preset--spacing--20);padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0\"><blockquote><p>\u00ab La Station d\u2019\u00e9coute de Boundary Pass est essentielle pour comprendre les \u00e9missions sonores de la flotte mondiale de navires commerciaux et leur incidence sur l\u2019environnement. En aidant \u00e0 d\u00e9finir les seuils de bruit pour les certifications internationales de navires silencieux, ces mesures permettront de r\u00e9duire le bruit dans tous les oc\u00e9ans du monde \u2013 un objectif essentiel pour assurer la sant\u00e9 et la survie des esp\u00e8ces en p\u00e9ril, y compris nos \u00e9paulards r\u00e9sidents du Sud \u00bb.<\/p><cite>David Hannay, directeur scientifique de JASCO<\/cite><\/blockquote><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Le d\u00e9troit et la mer des Salish qui l\u2019entoure constituent un habitat essentiel pour les <a href=\"https:\/\/parcs.canada.ca\/pn-np\/bc\/gulf\/nature\/ocean\/erds-srkw\/epaulard-killerwhale\">\u00e9paulards r\u00e9sidents du Sud<\/a>, une esp\u00e8ce menac\u00e9e. Le bruit sous-marin produit par les navires est consid\u00e9r\u00e9 comme une menace importante pour leur r\u00e9tablissement. Parrain\u00e9e par Transports Canada et en collaboration avec le <a href=\"https:\/\/www.portvancouver.com\/fr\/la-sante-des-ecosystemes\">Programme ECHO (Am\u00e9lioration de l\u2019habitat et de l\u2019observation des c\u00e9tac\u00e9s)<\/a> du Port de Vancouver, la station recueille des donn\u00e9es pour mesurer le bruit sous-marin des navires commerciaux, pour d\u00e9tecter la pr\u00e9sence de mammif\u00e8res marins \u00e0 proximit\u00e9 des voies de transport maritime et pour suivre les niveaux de bruit ambiant dans l\u2019oc\u00e9an au fil du temps.<\/p>\n\n\n\n\t\n\t\n\n\t<div class=\"accordion style-large align wp-block-acf-tu-accordion\">\n\t\t\n\t\t\t\t\t\n\t\t\t<div class=\"accordion-item\" \t\t\t\t data-aos=\"fade-up\">\n\t\t\t\t<button class=\"accordion-button no-btn-style\" aria-controls=\"content-1\"\n\t\t\t\t\t\taria-expanded=\"false\"\n\t\t\t\t\t\tid=\"accordion-control-1\" >\u00c9couter des enregistrements d&#8217;hydrophones de baleines et de navires<\/button>\n\n\t\t\t\t<div class=\"accordion-content\" aria-hidden=\"true\"\n\t\t\t\t\t id=\"content-1\" >\n\t\t\t\t\t\n\t\t\t\t\t<p>\u00c9coutez des sons \u00e9mis par des mammif\u00e8res marins et enregistr\u00e9s par la station d\u2019\u00e9coute sous-marine :<\/p>\n<p><a href=\"https:\/\/youtu.be\/-DQos2T2vOw\">\u00c9paulards r\u00e9sidents du Sud<\/a><\/p>\n<p><a href=\"https:\/\/youtu.be\/YwuaT3jigHg\">\u00c9paulards de Bigg (transitoires)<\/a><\/p>\n<p><a href=\"https:\/\/youtu.be\/sK3mVqrwLg0\">Baleines \u00e0 bosse<\/a><\/p>\n<p>\u00c9coutez des navires enregistr\u00e9s en zone c\u00f4ti\u00e8re :<\/p>\n<p><a href=\"https:\/\/hearmyship.fer.hr\/?page=1\" target=\"_blank\" rel=\"noopener\">Hear My Ship<\/a><\/p>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t\n\n\n\n\t\n\t\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 partir de mai 2020, la station a recueilli des donn\u00e9es sur le bruit sous-marin produit par pr\u00e8s de 10\u00a0000 navires uniques effectuant plus de 62\u00a0000 passages, cr\u00e9ant ainsi la plus grande base de donn\u00e9es non militaire au monde sur le bruit rayonn\u00e9 sous-marin. Ces donn\u00e9es peuvent \u00eatre utilis\u00e9es en combinaison avec d\u2019autres ensembles de donn\u00e9es \u2013 notamment la m\u00e9t\u00e9o, des photos et des vid\u00e9os, ainsi que la vitesse et la position des navires \u00e0 partir du SIA (Syst\u00e8me d\u2019identification automatique ou AIS en anglais) \u2013 pour soutenir la recherche dans un certain nombre de domaines. Les applications de recherche comprennent notamment le suivi des baleines, l\u2019identification des sons \u00e9mis par les poissons, la caract\u00e9risation de l\u2019habitat marin au fil du temps, la r\u00e9duction du bruit g\u00e9n\u00e9r\u00e9 par les navires commerciaux et le suivi des petits navires d\u00e9pourvus de transpondeurs SIA.<\/p>\n\n\n\n\t\n\t\n\n\t<div class=\"accordion style-large align wp-block-acf-tu-accordion\">\n\t\t\n\t\t\t\t\t\n\t\t\t<div class=\"accordion-item\" \t\t\t\t data-aos=\"fade-up\">\n\t\t\t\t<button class=\"accordion-button no-btn-style\" aria-controls=\"content-1\"\n\t\t\t\t\t\taria-expanded=\"false\"\n\t\t\t\t\t\tid=\"accordion-control-1\" >Une source de bruit inattendue<\/button>\n\n\t\t\t\t<div class=\"accordion-content\" aria-hidden=\"true\"\n\t\t\t\t\t id=\"content-1\" >\n\t\t\t\t\t\n\t\t\t\t\t<p>Les algues, les balanes, les vers tubicoles et d\u2019autres organismes marins peuvent se fixer \u00e0 la coque des navires au fil du temps \u2013 un processus appel\u00e9 <a href=\"#biofouling\">encrassement biologique<\/a>.<\/p>\n<p>La surface, autrefois lisse, devient rugueuse, ce qui cr\u00e9e une r\u00e9sistance (et du bruit) lorsque le navire se d\u00e9place dans l\u2019eau. Les navires recouverts d\u2019encrassement biologique consomment plus d\u2019\u00e9nergie pour se d\u00e9placer \u00e0 la m\u00eame vitesse comparativement \u00e0 une coque propre.<\/p>\n<p>L\u2019une des m\u00e9thodes permettant de r\u00e9duire l\u2019encrassement biologique consiste \u00e0 utiliser un syst\u00e8me qui \u00e9met des ondes sonores \u00e0 haute fr\u00e9quence pour emp\u00eacher les organismes marins de se fixer sur la coque.<\/p>\n<p>Les hydrophones de la Station d\u2019\u00e9coute sous-marine du passage Boundary ont pu capter le bruit d\u2019un navire utilisant cette technologie antisalissure et les chercheurs ont constat\u00e9 que la fr\u00e9quence du son \u00e9mis correspondait \u00e0 la fr\u00e9quence utilis\u00e9e par les \u00e9paulards r\u00e9sidents du Sud pour l\u2019\u00e9cholocalisation.<\/p>\n<p>Cela signifie que les \u00e9paulards peuvent avoir plus de difficult\u00e9s \u00e0 chasser, \u00e0 naviguer et \u00e0 communiquer entre eux lorsque des nettoyeurs de coques soniques sont utilis\u00e9s.<\/p>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t\n\n\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\">Cet article fait partie d&#8217;une s\u00e9rie de cinq articles sur la technologie de d\u00e9tection et d&#8217;analyse du bruit sous-marin des navires.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-3e41869c wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-50\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/clearseas.org\/fr\/insights\/initiatives-du-canada-bruit-sous-marin\/\">Article pr\u00e9c\u00e9dent<\/a><\/div>\n\n\n\n<div class=\"wp-block-button has-custom-width wp-block-button__width-50\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/clearseas.org\/fr\/insights\/lenjeu-de-la-profondeur\/\">Article suivant<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:2em\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Pour en savoir plus sur les nouvelles d\u00e9couvertes et les d\u00e9fis \u00e0 relever pour rendre les navires plus silencieux, consultez les autres sujets de cette s\u00e9rie ici.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-3e41869c wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-50\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/clearseas.org\/fr\/research\/qvi-technologie-conception-operations\/\">Consulter la s\u00e9rie<\/a><\/div>\n\n\n\n<div class=\"wp-block-button has-custom-width wp-block-button__width-50\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/clearseas.org\/bruits-sous-marins\/\">Visiter le microsite<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:2em\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><em>L&#8217;Initiative pour des navires silencieux est financ\u00e9e par le gouvernement f\u00e9d\u00e9ral par l&#8217;interm\u00e9diaire de Transports Canada. Les partenaires industriels et les chercheurs int\u00e9ress\u00e9s par d&#8217;\u00e9ventuelles collaborations en mati\u00e8re de recherche et de d\u00e9veloppement afin de faire progresser les solutions novatrices dans le domaine de la technologie marine sont invit\u00e9s \u00e0 contacter l&#8217;\u00e9quipe de l&#8217;Initiative pour des navires silencieux \u00e0 l&#8217;adresse suivante : <a href=\"mailto:Marine-RDD-maritime@tc.gc.ca\">Marine-RDD-maritime@tc.gc.ca<\/a>.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cr\u00e9dit image couverture\u00a0: <em><a href=\"https:\/\/unsplash.com\/@introspectivedsgn\"><em><a href=\"https:\/\/unsplash.com\/fr\/@lukephotography\">Keith Luke via Unsplash<\/a><\/em><\/a><\/em><\/p>\n<\/div>\n\n\n<div id=\"hydrophone\" class=\"basic-popup\">\n    <div class=\"popup-overlay\"><\/div>\n    <div class=\"popup-content\">\n        <div class=\"popup-content-inner\">\n            <div class=\"popup-content-header\">\n                <span class=\"popup-close\"><i class=\"far fa-times\"><\/i><\/span>\n            <\/div>\n            <div class=\"popup-content-body\">\n                \n\n<p class=\"wp-block-paragraph\"><strong>Hydrophone\u00a0<\/strong>: Microphone sous-marin qui peut \u00eatre d\u00e9ploy\u00e9 individuellement ou en groupe. Les groupes d\u2019hydrophones peuvent \u00eatre dispos\u00e9s horizontalement sur le fond marin ou verticalement \u00e0 diff\u00e9rentes profondeurs de la colonne d\u2019eau. Les hydrophones d\u00e9tectent les variations de pression dans l\u2019eau caus\u00e9es par les ondes sonores. Ces capteurs convertissent les fluctuations de pression sous-marine en signaux \u00e9lectriques, qui peuvent ensuite \u00eatre analys\u00e9s pour d\u00e9terminer les propri\u00e9t\u00e9s du son, comme le volume et la fr\u00e9quence.<\/p>\n\n\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<script>\n    \/\/ Check if the array exists; if not, initialize it\n    var validPopupIds = validPopupIds || [];\n    validPopupIds.push(\"hydrophone\");\n<\/script>\n\n<div id=\"decibel\" class=\"basic-popup\">\n    <div class=\"popup-overlay\"><\/div>\n    <div class=\"popup-content\">\n        <div class=\"popup-content-inner\">\n            <div class=\"popup-content-header\">\n                <span class=\"popup-close\"><i class=\"far fa-times\"><\/i><\/span>\n            <\/div>\n            <div class=\"popup-content-body\">\n                \n\n<p class=\"wp-block-paragraph\"><strong>D\u00e9cibel\u00a0<\/strong>: Unit\u00e9 utilis\u00e9e pour mesurer le niveau de pression acoustique (intensit\u00e9 d\u2019un son) ou le niveau de puissance d\u2019un signal \u00e9lectrique. Il s\u2019agit d\u2019une unit\u00e9 relative et non absolue, utilis\u00e9e pour exprimer une variation relative. Le d\u00e9cibel est utilis\u00e9 pour d\u00e9crire les sons en termes d\u2019intensit\u00e9. Pour les sons sous-marins, on utilise une pression de r\u00e9f\u00e9rence de 1 micropascal (\u03bcPa) pour d\u00e9crire les sons en termes de d\u00e9cibels.<\/p>\n\n\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<script>\n    \/\/ Check if the array exists; if not, initialize it\n    var validPopupIds = validPopupIds || [];\n    validPopupIds.push(\"decibel\");\n<\/script>\n\n<div id=\"intensity\" class=\"basic-popup\">\n    <div class=\"popup-overlay\"><\/div>\n    <div class=\"popup-content\">\n        <div class=\"popup-content-inner\">\n            <div class=\"popup-content-header\">\n                <span class=\"popup-close\"><i class=\"far fa-times\"><\/i><\/span>\n            <\/div>\n            <div class=\"popup-content-body\">\n                \n\n<p class=\"wp-block-paragraph\"><strong>Intensit\u00e9\u00a0<\/strong>: Quantit\u00e9 d\u2019\u00e9nergie contenue dans une onde sonore, mesur\u00e9e dans une zone donn\u00e9e \u00e0 un moment donn\u00e9; se traduit \u00e9galement par la perception subjective de la pression acoustique et de l\u2019intensit\u00e9 sonore.<\/p>\n\n\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<script>\n    \/\/ Check if the array exists; if not, initialize it\n    var validPopupIds = validPopupIds || [];\n    validPopupIds.push(\"intensity\");\n<\/script>\n\n<div id=\"underwater_noise\" class=\"basic-popup\">\n    <div class=\"popup-overlay\"><\/div>\n    <div class=\"popup-content\">\n        <div class=\"popup-content-inner\">\n            <div class=\"popup-content-header\">\n                <span class=\"popup-close\"><i class=\"far fa-times\"><\/i><\/span>\n            <\/div>\n            <div class=\"popup-content-body\">\n                \n\n<p class=\"wp-block-paragraph\"><strong>Bruit sous-marin\u00a0<\/strong>: Bruit g\u00e9n\u00e9r\u00e9 sous l\u2019eau par l\u2019activit\u00e9 humaine dans l\u2019environnement oc\u00e9anique. Diverses industries contribuent au bruit sous-marin : la production \u00e9nerg\u00e9tique extrac\u00f4ti\u00e8re, les travaux de construction, les op\u00e9rations militaires et, bien s\u00fbr, le trafic maritime. Le bruit g\u00e9n\u00e9r\u00e9 par les navires est appel\u00e9 bruit rayonn\u00e9 sous-marin.<\/p>\n\n\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<script>\n    \/\/ Check if the array exists; if not, initialize it\n    var validPopupIds = validPopupIds || [];\n    validPopupIds.push(\"underwater_noise\");\n<\/script>\n\n<div id=\"biofouling\" class=\"basic-popup\">\n    <div class=\"popup-overlay\"><\/div>\n    <div class=\"popup-content\">\n        <div class=\"popup-content-inner\">\n            <div class=\"popup-content-header\">\n                <span class=\"popup-close\"><i class=\"far fa-times\"><\/i><\/span>\n            <\/div>\n            <div class=\"popup-content-body\">\n                \n\n<p class=\"wp-block-paragraph\"><strong>Encrassement biologique&nbsp;:<\/strong> Accumulation d\u2019organismes vivants sur la coque et d\u2019autres parties immerg\u00e9es d\u2019un navire, qui entra\u00eene une augmentation de la \u00ab tra\u00een\u00e9e \u00bb ou de la friction lorsque le navire est en d\u00e9placement. Cette tra\u00een\u00e9e augmente le bruit et diminue l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique du navire.<\/p>\n\n\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<script>\n    \/\/ Check if the array exists; if not, initialize it\n    var validPopupIds = validPopupIds || [];\n    validPopupIds.push(\"biofouling\");\n<\/script>\n\n<ol class=\"wp-block-footnotes\"><li id=\"916c8151-312f-44fa-8ba0-67dfe332d99c\">Les armateurs, les concepteurs, les exploitants et les autres intervenants peuvent utiliser la norme de mesure du bruit la plus appropri\u00e9e et la plus r\u00e9cente figurant dans les directives r\u00e9vis\u00e9es de l\u2019OMI sur la r\u00e9duction du bruit sous-marin produit par les navires en vue de rem\u00e9dier aux effets n\u00e9fastes sur la vie marine. <a href=\"#916c8151-312f-44fa-8ba0-67dfe332d99c-link\" aria-label=\"Jump to footnote reference 1\">\u21a9\ufe0e<\/a><\/li><\/ol>","protected":false},"excerpt":{"rendered":"<p>La mesure pr\u00e9cise du bruit sous-marin, \u00e0 l&#8217;aide d&#8217;hydrophones et de port\u00e9es acoustiques, est essentielle pour les chercheurs, les r\u00e9gulateurs et les op\u00e9rateurs de navires afin de comprendre l&#8217;impact du bruit sur la vie marine.<\/p>\n","protected":false},"author":14,"featured_media":23309,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"[{\"id\":\"916c8151-312f-44fa-8ba0-67dfe332d99c\",\"content\":\"Les armateurs, les concepteurs, les exploitants et les autres intervenants peuvent utiliser la norme de mesure du bruit la plus appropri\\u00e9e et la plus r\\u00e9cente figurant dans les directives r\\u00e9vis\\u00e9es de l\\u2019OMI sur la r\\u00e9duction du bruit sous-marin produit par les navires en vue de rem\\u00e9dier aux effets n\\u00e9fastes sur la vie marine.\"}]","jetpack_post_was_ever_published":false},"categories":[1017,1021],"tags":[],"insight_type":[76],"class_list":["post-23334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-impacts-environnementaux-du-transport-maritime","category-technologie-et-innovation-marines","insight_type-articles-fr"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/clearseas.org\/wp-content\/uploads\/keith-luke-dKe9GgzS8Ek-unsplash-scaled.jpg?fit=2560%2C1707&ssl=1","acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/clearseas.org\/fr\/wp-json\/wp\/v2\/posts\/23334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clearseas.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clearseas.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clearseas.org\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/clearseas.org\/fr\/wp-json\/wp\/v2\/comments?post=23334"}],"version-history":[{"count":15,"href":"https:\/\/clearseas.org\/fr\/wp-json\/wp\/v2\/posts\/23334\/revisions"}],"predecessor-version":[{"id":23408,"href":"https:\/\/clearseas.org\/fr\/wp-json\/wp\/v2\/posts\/23334\/revisions\/23408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clearseas.org\/fr\/wp-json\/wp\/v2\/media\/23309"}],"wp:attachment":[{"href":"https:\/\/clearseas.org\/fr\/wp-json\/wp\/v2\/media?parent=23334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clearseas.org\/fr\/wp-json\/wp\/v2\/categories?post=23334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clearseas.org\/fr\/wp-json\/wp\/v2\/tags?post=23334"},{"taxonomy":"insight_type","embeddable":true,"href":"https:\/\/clearseas.org\/fr\/wp-json\/wp\/v2\/insight_type?post=23334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}